{"id":668,"date":"2017-12-29T09:08:52","date_gmt":"2017-12-29T09:08:52","guid":{"rendered":"http:\/\/www.dentalsbay.com\/?p=668"},"modified":"2017-12-29T09:08:52","modified_gmt":"2017-12-29T09:08:52","slug":"consejos-practicos-para-prevenir-problemas-de-salud-en-tus-encias","status":"publish","type":"post","link":"https:\/\/www.dentalsbay.com\/index.php\/2017\/12\/29\/consejos-practicos-para-prevenir-problemas-de-salud-en-tus-encias\/","title":{"rendered":"CONSEJOS PR\u00c1CTICOS PARA PREVENIR PROBLEMAS DE SALUD EN TUS ENC\u00cdAS"},"content":{"rendered":"<p>Si por el momento no tienes problemas gingivales, te animamos a la prevenci\u00f3n. Muchos pacientes dar\u00edan lo que fuera por haber recibido un consejo a tiempo.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/silmidental.com\/wp-content\/uploads\/2017\/10\/Curetaje-dental-1100x823.jpg\" alt=\"Curetaje dental - Blog Silmidental\" width=\"500\" \/><\/p>\n<p>En SilmiDental le damos una gran importancia y prioridad a prevenir los factores etiol\u00f3gicos. Somos expertos tanto en adelantarnos a los posibles problemas ,como en su detecci\u00f3n precoz y tratamiento.<\/p>\n<p>Cuida tu higiene dental.No se trata solo de cumplir con cepillarse los dientes tres veces al d\u00eda, sino que adem\u00e1s es importante lavarlos bien. Aseg\u00farate de proteger tus dientes con cepillados de dos o tres minutos, llegando a todos los rincones de la boca. Adem\u00e1s, evita movimientos demasiado agresivos, especialmente si tus enc\u00edas est\u00e1s inflamadas.<br \/>\nAcude al dentista con regularidad, al menos dos veces al a\u00f1o, para asegurarte de que tu salud buco-dental est\u00e1<br \/>\nSi tienes gingivitis o cualquier otra dolencia dental, trata a tiempo el problema para evitar que se acumule m\u00e1s placa bacteriana y que se produzca una retracci\u00f3n de las enc\u00edas.<\/p>\n<p><strong>CONSULTA TU CASO EN NUESTRA CL\u00cdNICA DENTAL<\/strong><\/p>\n<p>Si tiene cualquier duda o consulta no dude en pedir cita en nuestra Cl\u00ednica Silmidental. El Dr. Silmi har\u00e1 una valoraci\u00f3n con diagn\u00f3stico para poder ofrecerle las mejores alternativas en su caso concreto. Pida cita, sin compromiso, la primer visita es gratuita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si por el momento no tienes problemas gingivales, te animamos a la prevenci\u00f3n. Muchos pacientes dar\u00edan lo que fuera por haber recibido un consejo a tiempo. En SilmiDental le damos una gran importancia y prioridad a prevenir los factores etiol\u00f3gicos. Somos expertos tanto en adelantarnos a los posibles problemas ,como en su detecci\u00f3n precoz y &hellip; <a href=\"https:\/\/www.dentalsbay.com\/index.php\/2017\/12\/29\/consejos-practicos-para-prevenir-problemas-de-salud-en-tus-encias\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;CONSEJOS PR\u00c1CTICOS PARA PREVENIR PROBLEMAS DE SALUD EN TUS ENC\u00cdAS&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-668","post","type-post","status-publish","format-standard","hentry","category-noticias-dental"],"_links":{"self":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts\/668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/comments?post=668"}],"version-history":[{"count":1,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts\/668\/revisions"}],"predecessor-version":[{"id":669,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts\/668\/revisions\/669"}],"wp:attachment":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/media?parent=668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/categories?post=668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/tags?post=668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}