{"id":666,"date":"2017-12-23T09:47:00","date_gmt":"2017-12-23T09:47:00","guid":{"rendered":"http:\/\/www.dentalsbay.com\/?p=666"},"modified":"2017-12-23T09:47:00","modified_gmt":"2017-12-23T09:47:00","slug":"complicaciones-con-la-integracion-del-implante-en-el-hueso","status":"publish","type":"post","link":"https:\/\/www.dentalsbay.com\/index.php\/2017\/12\/23\/complicaciones-con-la-integracion-del-implante-en-el-hueso\/","title":{"rendered":"Complicaciones con la integraci\u00f3n del implante en el hueso"},"content":{"rendered":"<p>Si bien la reposici\u00f3n de piezas ausentes mediante <a href=\"https:\/\/www.youtube.com\/watch?v=k_xSY0pW4yc\">implantes dentales<\/a> tiene un porcentaje de \u00e9xito que supera el 90%, este tipo de tratamientos no est\u00e1 exento de complicaciones que pueden hacerlo fracasar.<\/p>\n<p>Cuando se coloca un implante dental en el hueso maxilar comienza un proceso que se denomina osteointegraci\u00f3n, el cual consiste en la uni\u00f3n directa, estructural y funcional entre el implante dental y el hueso alveolar.<\/p>\n<p>Para conseguir el \u00e9xito de este proceso de integraci\u00f3n, al colocar el implante debe haber una estabilidad primaria que garantice dicha uni\u00f3n, y hay que esperar un m\u00ednimo de tres meses hasta poder cargar el implante con la pr\u00f3tesis definitiva.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.segurcaixaadeslas.es\/es\/particulares-sitio\/seguros-dentales-sitio\/informaciontratamientosdentales\/assets\/img\/article\/implantes-article-4.jpg\" alt=\"Riesgos, complicaciones y dolor de los implantes dentales\" width=\"500\" \/><\/p>\n<p><strong>Complicaciones con la integraci\u00f3n del implante en el hueso<\/strong><br \/>\nAdicionalmente existen una serie de factores de riesgo que pueden influir en dicho proceso de osteointegraci\u00f3n. Estos factores son principalmente el tabaquismo, ciertas enfermedades sist\u00e9micas como la diabetes, la cantidad y la calidad del hueso y la ingesta de ciertos medicamentos, entre otros.<\/p>\n<p>Una de las complicaciones tempranas durante el per\u00edodo de osteointegraci\u00f3n, es la movilidad del implante provocando la p\u00e9rdida de anclaje al hueso. En ocasiones, las causas de este fracaso son desconocidas, implicando la necesidad de repetir la fase quir\u00fargica, y en ciertos casos, replantear el tratamiento.<\/p>\n<p>A medio y largo plazo tambi\u00e9n pueden aparecer complicaciones que impliquen el fracaso del implante, como es la periimplantitis. El hecho de que el implante se haya integrado en el hueso en un primer momento no implica que no pueda fracasar posteriormente. Las causas del fracaso son m\u00faltiples, y muchas desconocidas: factores relacionados con la oclusi\u00f3n, con la higiene defectuosa, con la falta de revisiones peri\u00f3dicas, factores intr\u00ednsecos a la propia biolog\u00eda del paciente, etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si bien la reposici\u00f3n de piezas ausentes mediante implantes dentales tiene un porcentaje de \u00e9xito que supera el 90%, este tipo de tratamientos no est\u00e1 exento de complicaciones que pueden hacerlo fracasar. Cuando se coloca un implante dental en el hueso maxilar comienza un proceso que se denomina osteointegraci\u00f3n, el cual consiste en la uni\u00f3n &hellip; <a href=\"https:\/\/www.dentalsbay.com\/index.php\/2017\/12\/23\/complicaciones-con-la-integracion-del-implante-en-el-hueso\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Complicaciones con la integraci\u00f3n del implante en el hueso&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[53],"class_list":["post-666","post","type-post","status-publish","format-standard","hentry","category-implantes-dentales","tag-implante"],"_links":{"self":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts\/666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/comments?post=666"}],"version-history":[{"count":1,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts\/666\/revisions"}],"predecessor-version":[{"id":667,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/posts\/666\/revisions\/667"}],"wp:attachment":[{"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/media?parent=666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/categories?post=666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dentalsbay.com\/index.php\/wp-json\/wp\/v2\/tags?post=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}